{"id":144,"count":2,"description":"","link":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/montenegro\/","name":"Montenegro","slug":"montenegro","taxonomy":"category","parent":2,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/globalsmiletravel.com\/en\/category\/europe\/montenegro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/144\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/europe\\\/#listItem\",\"name\":\"Europe\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/europe\\\/#listItem\",\"position\":2,\"name\":\"Europe\",\"item\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/europe\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/europe\\\/montenegro\\\/#listItem\",\"name\":\"Montenegro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/europe\\\/montenegro\\\/#listItem\",\"position\":3,\"name\":\"Montenegro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/europe\\\/#listItem\",\"name\":\"Europe\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/144\\\/#collectionpage\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/144\\\/\",\"name\":\"Montenegro \\u2023 GlobalSmile travel\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/144\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#organization\",\"name\":\"GlobalSmile travel\",\"description\":\"Traveling the world with a GS: a Global Smile \\u30c4\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Global-Smile-logo-optrans_247x109.png\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/144\\\/#organizationLogo\",\"width\":247,\"height\":109},\"image\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/144\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlobalSmileTravel\",\"https:\\\/\\\/www.instagram.com\\\/globalsmiletravel\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbONFWZEhliFtwpzYuMw2bw\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/\",\"name\":\"GlobalSmile travel\",\"description\":\"Traveling the world with a GS: a Global Smile \\u30c4\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Montenegro \u2023 GlobalSmile travel","description":"","canonical_url":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/montenegro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories\/144\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/globalsmiletravel.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/#listItem","name":"Europe"}},{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/#listItem","position":2,"name":"Europe","item":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/","nextItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/montenegro\/#listItem","name":"Montenegro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/montenegro\/#listItem","position":3,"name":"Montenegro","previousItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/#listItem","name":"Europe"}}]},{"@type":"CollectionPage","@id":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories\/144\/#collectionpage","url":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories\/144\/","name":"Montenegro \u2023 GlobalSmile travel","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/globalsmiletravel.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories\/144\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/globalsmiletravel.com\/en\/#organization","name":"GlobalSmile travel","description":"Traveling the world with a GS: a Global Smile \u30c4","url":"https:\/\/globalsmiletravel.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2021\/12\/Global-Smile-logo-optrans_247x109.png","@id":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories\/144\/#organizationLogo","width":247,"height":109},"image":{"@id":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories\/144\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/GlobalSmileTravel","https:\/\/www.instagram.com\/globalsmiletravel","https:\/\/www.youtube.com\/channel\/UCbONFWZEhliFtwpzYuMw2bw"]},{"@type":"WebSite","@id":"https:\/\/globalsmiletravel.com\/en\/#website","url":"https:\/\/globalsmiletravel.com\/en\/","name":"GlobalSmile travel","description":"Traveling the world with a GS: a Global Smile \u30c4","inLanguage":"en-GB","publisher":{"@id":"https:\/\/globalsmiletravel.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/globalsmiletravel.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/globalsmiletravel.com\/en\/category\/europe\/\" title=\"Europe\">Europe<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMontenegro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/globalsmiletravel.com\/en"},{"label":"Europe","link":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/"},{"label":"Montenegro","link":"https:\/\/globalsmiletravel.com\/en\/category\/europe\/montenegro\/"}],"_links":{"self":[{"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories\/144"}],"collection":[{"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories\/2"}],"wp:post_type":[{"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/posts?categories=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}