{"id":2510,"date":"2023-04-26T12:24:39","date_gmt":"2023-04-26T12:24:39","guid":{"rendered":"https:\/\/globalsmiletravel.com\/?p=2510"},"modified":"2023-04-26T12:27:05","modified_gmt":"2023-04-26T12:27:05","slug":"een-uitdagende-beklimming","status":"publish","type":"post","link":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/","title":{"rendered":"A challenging climb"},"content":{"rendered":"<p><strong>Today we get a visit from the bridal couple, who will join us for a hike to the top of Hollow Mountain. And it turns out to be quite a challenge. In several places it is clambering instead of walking and we have to help each other to move on. However, the view is again impressive and makes up for it.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-810x1080.jpeg\" alt=\"\" class=\"wp-image-2471\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-760x1013.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6833-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-810x1080.jpeg\" alt=\"\" class=\"wp-image-2470\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-760x1013.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6829-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-810x1080.jpeg\" alt=\"\" class=\"wp-image-2475\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-760x1014.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6877-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p>After a joint overnight stay in our secluded bungalow, the bridal couple return home and we leave National Park The Grampians to drive back to Melbourne on The Great Ocean Road. Opened as early as 1932, this 150-mile (243 km) road lies between the towns of Torquay and Allansford and winds through the countryside close to the coast. There are many points with beautiful views and one of them is The Twelve Apostles. Of the 12 rocks that rise out of the water here, 8 are still standing. The other four have already fallen over due to erosion and the eternal pounding of the ocean.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-810x1080.jpeg\" alt=\"\" class=\"wp-image-2474\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-760x1013.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6872-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-810x1080.jpeg\" alt=\"\" class=\"wp-image-2476\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-760x1014.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6894-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p>Another stop is known for spotting koalas. We are lucky and can see 3, which unfortunately camp quite high in the trees.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-810x1080.jpeg\" alt=\"\" class=\"wp-image-2473\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-760x1013.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6871-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p>We spend the night in Apollo Bay, a small coastal village with a beautiful beach. After a pleasant evening in the local pub, everyone finds their own motel room and the next morning we have breakfast together in one room before continuing on the Great Ocean Road.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-810x1080.jpeg\" alt=\"\" class=\"wp-image-2477\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-760x1013.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6907-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-810x1080.jpeg\" alt=\"\" class=\"wp-image-2479\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-760x1013.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6913-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"810\" height=\"1080\" src=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-810x1080.jpeg\" alt=\"\" class=\"wp-image-2478\" srcset=\"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-810x1080.jpeg 810w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-225x300.jpeg 225w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-768x1024.jpeg 768w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-1152x1536.jpeg 1152w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-1536x2048.jpeg 1536w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-9x12.jpeg 9w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-1260x1680.jpeg 1260w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-760x1013.jpeg 760w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-860x1147.jpeg 860w, https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_2483-scaled.jpeg 1920w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>Today we get a visit from the bridal couple, who will join us for a hike to the top of Hollow Mountain. And it turns out to be quite a challenge. In several places it is clambering instead of walking and we have to help each other to move on. However, the view is again impressive and makes up for it&#8230;.<\/p>","protected":false},"author":1,"featured_media":2512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[161,160],"tags":[],"post_series":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Vandaag krijgen we bezoek van het bruidspaar, dat ons zal vergezellen voor een hike naar de top van Hollow Mountain. En het blijkt nogal een uitdaging. Op verschillende plekken is het klauteren in plaats van lopen en moeten we elkaar helpen om verder te kunnen. Het uitzicht is echter weer indrukwekkend en maakt alles goed.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"ivo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"GlobalSmile travel \u2023 Traveling the world with a GS: a Global Smile \u30c4\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Een uitdagende beklimming \u2023 GlobalSmile travel\" \/>\n\t\t<meta property=\"og:description\" content=\"Vandaag krijgen we bezoek van het bruidspaar, dat ons zal vergezellen voor een hike naar de top van Hollow Mountain. En het blijkt nogal een uitdaging. Op verschillende plekken is het klauteren in plaats van lopen en moeten we elkaar helpen om verder te kunnen. Het uitzicht is echter weer indrukwekkend en maakt alles goed.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-26T12:24:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-04-26T12:27:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlobalSmileTravel\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Een uitdagende beklimming \u2023 GlobalSmile travel\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Vandaag krijgen we bezoek van het bruidspaar, dat ons zal vergezellen voor een hike naar de top van Hollow Mountain. En het blijkt nogal een uitdaging. Op verschillende plekken is het klauteren in plaats van lopen en moeten we elkaar helpen om verder te kunnen. Het uitzicht is echter weer indrukwekkend en maakt alles goed.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#blogposting\",\"name\":\"Een uitdagende beklimming \\u2023 GlobalSmile travel\",\"headline\":\"Een uitdagende beklimming\",\"author\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IMG_6873-scaled.jpeg\",\"width\":2560,\"height\":1920},\"datePublished\":\"2023-04-26T12:24:39+00:00\",\"dateModified\":\"2023-04-26T12:27:05+00:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#webpage\"},\"articleSection\":\"Australia, Oceania\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/oceania\\\/#listItem\",\"name\":\"Oceania\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/oceania\\\/#listItem\",\"position\":2,\"name\":\"Oceania\",\"item\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/oceania\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/oceania\\\/australia\\\/#listItem\",\"name\":\"Australia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/oceania\\\/australia\\\/#listItem\",\"position\":3,\"name\":\"Australia\",\"item\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/oceania\\\/australia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#listItem\",\"name\":\"Een uitdagende beklimming\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/oceania\\\/#listItem\",\"name\":\"Oceania\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#listItem\",\"position\":4,\"name\":\"Een uitdagende beklimming\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/category\\\/oceania\\\/australia\\\/#listItem\",\"name\":\"Australia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#organization\",\"name\":\"GlobalSmile travel\",\"description\":\"Traveling the world with a GS: a Global Smile \\u30c4\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Global-Smile-logo-optrans_247x109.png\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#organizationLogo\",\"width\":247,\"height\":109},\"image\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlobalSmileTravel\",\"https:\\\/\\\/www.instagram.com\\\/globalsmiletravel\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbONFWZEhliFtwpzYuMw2bw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/author\\\/admin\\\/\",\"name\":\"ivo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b32a0b69a7553b9bfeb1bb937276651e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"ivo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#webpage\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/\",\"name\":\"Een uitdagende beklimming \\u2023 GlobalSmile travel\",\"description\":\"Vandaag krijgen we bezoek van het bruidspaar, dat ons zal vergezellen voor een hike naar de top van Hollow Mountain. En het blijkt nogal een uitdaging. Op verschillende plekken is het klauteren in plaats van lopen en moeten we elkaar helpen om verder te kunnen. Het uitzicht is echter weer indrukwekkend en maakt alles goed.\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/IMG_6873-scaled.jpeg\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#mainImage\",\"width\":2560,\"height\":1920},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/een-uitdagende-beklimming\\\/#mainImage\"},\"datePublished\":\"2023-04-26T12:24:39+00:00\",\"dateModified\":\"2023-04-26T12:27:05+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/\",\"name\":\"GlobalSmile travel\",\"description\":\"Traveling the world with a GS: a Global Smile \\u30c4\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalsmiletravel.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Een uitdagende beklimming \u2023 GlobalSmile travel","description":"Today we get a visit from the bridal couple, who will join us for a hike to the top of Hollow Mountain. And it turns out to be quite a challenge. In several places it is clambering instead of walking and we have to help each other to move on. However, the view is again impressive and makes up for it.","canonical_url":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#blogposting","name":"Een uitdagende beklimming \u2023 GlobalSmile travel","headline":"Een uitdagende beklimming","author":{"@id":"https:\/\/globalsmiletravel.com\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/globalsmiletravel.com\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6873-scaled.jpeg","width":2560,"height":1920},"datePublished":"2023-04-26T12:24:39+00:00","dateModified":"2023-04-26T12:27:05+00:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#webpage"},"isPartOf":{"@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#webpage"},"articleSection":"Australia, Oceania"},{"@type":"BreadcrumbList","@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/globalsmiletravel.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/#listItem","name":"Oceania"}},{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/#listItem","position":2,"name":"Oceania","item":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/","nextItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/australia\/#listItem","name":"Australia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/australia\/#listItem","position":3,"name":"Australia","item":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/australia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#listItem","name":"Een uitdagende beklimming"},"previousItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/#listItem","name":"Oceania"}},{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#listItem","position":4,"name":"Een uitdagende beklimming","previousItem":{"@type":"ListItem","@id":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/australia\/#listItem","name":"Australia"}}]},{"@type":"Organization","@id":"https:\/\/globalsmiletravel.com\/en\/#organization","name":"GlobalSmile travel","description":"Traveling the world with a GS: a Global Smile \u30c4","url":"https:\/\/globalsmiletravel.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2021\/12\/Global-Smile-logo-optrans_247x109.png","@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#organizationLogo","width":247,"height":109},"image":{"@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/GlobalSmileTravel","https:\/\/www.instagram.com\/globalsmiletravel","https:\/\/www.youtube.com\/channel\/UCbONFWZEhliFtwpzYuMw2bw"]},{"@type":"Person","@id":"https:\/\/globalsmiletravel.com\/en\/author\/admin\/#author","url":"https:\/\/globalsmiletravel.com\/en\/author\/admin\/","name":"ivo","image":{"@type":"ImageObject","@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b32a0b69a7553b9bfeb1bb937276651e?s=96&d=mm&r=g","width":96,"height":96,"caption":"ivo"}},{"@type":"WebPage","@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#webpage","url":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/","name":"Een uitdagende beklimming \u2023 GlobalSmile travel","description":"Vandaag krijgen we bezoek van het bruidspaar, dat ons zal vergezellen voor een hike naar de top van Hollow Mountain. En het blijkt nogal een uitdaging. Op verschillende plekken is het klauteren in plaats van lopen en moeten we elkaar helpen om verder te kunnen. Het uitzicht is echter weer indrukwekkend en maakt alles goed.","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/globalsmiletravel.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#breadcrumblist"},"author":{"@id":"https:\/\/globalsmiletravel.com\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/globalsmiletravel.com\/en\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/globalsmiletravel.com\/wp-content\/uploads\/2023\/04\/IMG_6873-scaled.jpeg","@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#mainImage","width":2560,"height":1920},"primaryImageOfPage":{"@id":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/#mainImage"},"datePublished":"2023-04-26T12:24:39+00:00","dateModified":"2023-04-26T12:27:05+00:00"},{"@type":"WebSite","@id":"https:\/\/globalsmiletravel.com\/en\/#website","url":"https:\/\/globalsmiletravel.com\/en\/","name":"GlobalSmile travel","description":"Traveling the world with a GS: a Global Smile \u30c4","inLanguage":"en-GB","publisher":{"@id":"https:\/\/globalsmiletravel.com\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"GlobalSmile travel \u2023 Traveling the world with a GS: a Global Smile \u30c4","og:type":"article","og:title":"Een uitdagende beklimming \u2023 GlobalSmile travel","og:description":"Vandaag krijgen we bezoek van het bruidspaar, dat ons zal vergezellen voor een hike naar de top van Hollow Mountain. En het blijkt nogal een uitdaging. Op verschillende plekken is het klauteren in plaats van lopen en moeten we elkaar helpen om verder te kunnen. Het uitzicht is echter weer indrukwekkend en maakt alles goed.","og:url":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/","article:published_time":"2023-04-26T12:24:39+00:00","article:modified_time":"2023-04-26T12:27:05+00:00","article:publisher":"https:\/\/www.facebook.com\/GlobalSmileTravel","twitter:card":"summary","twitter:title":"Een uitdagende beklimming \u2023 GlobalSmile travel","twitter:description":"Vandaag krijgen we bezoek van het bruidspaar, dat ons zal vergezellen voor een hike naar de top van Hollow Mountain. En het blijkt nogal een uitdaging. Op verschillende plekken is het klauteren in plaats van lopen en moeten we elkaar helpen om verder te kunnen. Het uitzicht is echter weer indrukwekkend en maakt alles goed."},"aioseo_meta_data":{"post_id":"2510","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-04-26 12:24:42","updated":"2025-06-04 18:38:13","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/globalsmiletravel.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/\" title=\"Oceania\">Oceania<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/australia\/\" title=\"Australia\">Australia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEen uitdagende beklimming\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/globalsmiletravel.com\/en"},{"label":"Oceania","link":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/"},{"label":"Australia","link":"https:\/\/globalsmiletravel.com\/en\/category\/oceania\/australia\/"},{"label":"Een uitdagende beklimming","link":"https:\/\/globalsmiletravel.com\/en\/een-uitdagende-beklimming\/"}],"_links":{"self":[{"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/posts\/2510"}],"collection":[{"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/comments?post=2510"}],"version-history":[{"count":1,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/posts\/2510\/revisions"}],"predecessor-version":[{"id":2511,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/posts\/2510\/revisions\/2511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/media\/2512"}],"wp:attachment":[{"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/media?parent=2510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/categories?post=2510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/tags?post=2510"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/globalsmiletravel.com\/en\/wp-json\/wp\/v2\/post_series?post=2510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}